{"id":2468,"date":"2014-06-16T00:38:33","date_gmt":"2014-06-15T22:38:33","guid":{"rendered":"http:\/\/www.borsig11.de\/wordpress\/?p=2468"},"modified":"2015-08-09T02:27:41","modified_gmt":"2015-08-09T00:27:41","slug":"borsig-guerilla","status":"publish","type":"post","link":"https:\/\/www.borsig11.de\/wordpress\/2014\/06\/borsig-guerilla\/","title":{"rendered":"BORSIG-GUERILLA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2469\" src=\"https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2014\/06\/10336756_684241051646602_1722653293387136737_n.jpg\" alt=\"10336756_684241051646602_1722653293387136737_n\" width=\"600\" height=\"304\" srcset=\"https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2014\/06\/10336756_684241051646602_1722653293387136737_n.jpg 765w, https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2014\/06\/10336756_684241051646602_1722653293387136737_n-300x152.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>BORSIG-GUERILLA? &#8211; DA KANN JA JEDE(R) KOMMEN!<\/strong><\/p>\n<p>Richtig, wenn Du zwischen 18-26 Jahre alt bist und mit zehn Komplizen\/innen deiner Generation, den \u00f6ffentlichen Raum im Borsigviertel mitgestalten m\u00f6chtest &#8211; Herzlich Willkommen!<\/p>\n<p>Ein vorgefertigtes Konzept gibt es nicht! Du bist der\/die Lokalexperten\/in. Keiner wei\u00df besser als Du, wie es sich in Deinem Viertel leben l\u00e4sst und welche Probleme und Vorz\u00fcge der Alltag in deinem Stadtteil mit sich bringt. Deine Alltagserfahrungen und Zukunftspl\u00e4ne, als junge(r) Erwachsene(r) und Bewohner\/innen des Borsigviertels, sind die ideale Basis, um gezielt und kreativ auf das aktuelle Geschehen in Deiner Umgebung Einfluss zu nehmen.<\/p>\n<p><strong>DIE BORSIG-GUERILLA EINGANGSFRAGEN:<\/strong><\/p>\n<p>Ich halte Ausschau nach Euren Borsig-Visionen: Schreibt mir, hinterlasst Antworten und Anregungen, oder lasst uns ganz in Eurer N\u00e4he auf \u00a0&#8217;nen Kaffee treffen, denn folgende Fragen interessieren mich brennend:<\/p>\n<p>Wer getstaltet wie den \u00f6ffentliche Raum im Borsigviertel?<\/p>\n<p>Wie w\u00fcrdest Du gerne Einfluss nehmen auf die zuk\u00fcnftige Entwicklung im Quartier?<\/p>\n<p>Was m\u00fcsste sich ver\u00e4ndern, damit sich Dein Stadtteil f\u00fcr Dich, Deine Nachbarn und Gastbesucher, durch eine gute Atmosph\u00e4re, Wohn- und Lebensqualit\u00e4t auszeichnet?<\/p>\n<p>Was soll eben nicht ver\u00e4ndert werden? Vor welchen Entwicklungstrends sollten die lokalen Gepflogenheiten und Traditionen bewahrt werden?<\/p>\n<p>Welche Deiner Interessen, F\u00e4higkeiten, vielleicht auch ungeahnten Talente und M\u00f6glichkeiten, m\u00f6chtest Du als Guerilla-Akteur\/in in einem gesch\u00fctzten Rahmen ausprobieren? &#8211; Auch in Hinblick auf deine weitere pers\u00f6nliche und berufliche Zukunft?<\/p>\n<p><strong>DAS BORSIG &#8211; GUERILLA BASISLAGER<\/strong><\/p>\n<p>R\u00fcckendeckung bekommen wir von dem Verein Machbarschaft Borsig11\u00a0und seinem engagierten Team, das dieses Vorhaben \u00fcberhaupt erst m\u00f6glich gemacht hat, gut vernetzt ist und uns f\u00fcr den Anfang einen attraktiven Treffpunkt zur Verf\u00fcgung stellt:\u00a0Direkt am Borsigplatz \u2013 Nr.9!<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2404\" src=\"https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2014\/06\/angela100.jpg\" alt=\"angela100\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2014\/06\/angela100.jpg 100w, https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2014\/06\/angela100-90x90.jpg 90w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><strong>Angela Ljiljanic<\/strong><br \/>\nemail: <a title=\"Email an Angela Ljiljanic\" href=\"mailto:angela@borsig11.de\">angela@borsig11.de<\/a><br \/>\nfacebook: <a title=\"facebook Borsig-Guerilla\" href=\"https:\/\/www.facebook.com\/pages\/Borsig-Guerilla\/684195311651176\" target=\"_blank\">Borsig-Guerilla<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Die &#8222;BORSIG-GUERILLA&#8220; ist eine Aktion von\u00a0Angela Ljiljanic<br \/>\nim Rahmen von\u00a0<a title=\"Public Residence: Die Chance\" href=\"https:\/\/www.borsig11.de\/wordpress\/public-residence\/\">PUBLIC RESIDENCE: DIE CHANCE<\/a><br \/>\nein Projekt von\u00a0<a title=\"Machbarschaft Borsig11\" href=\"https:\/\/www.borsig11.de\/wordpress\/info\/\">Machbarschaft Borsig11<\/a><br \/>\nin Kooperation mit:<\/p>\n<p><a href=\"http:\/\/www.montag-stiftungen.de\/kunst-und-gesellschaft\/stiftung-kunst-und-gesellschaft.html\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1663\" src=\"https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2013\/11\/montag.png\" alt=\"montag\" width=\"249\" height=\"55\" srcset=\"https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2013\/11\/montag.png 408w, https:\/\/www.borsig11.de\/wordpress\/wp-content\/uploads\/2013\/11\/montag-300x66.png 300w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BORSIG-GUERILLA? &#8211; DA KANN JA JEDE(R) KOMMEN! Richtig, wenn Du zwischen 18-26 Jahre alt bist und mit zehn Komplizen\/innen deiner Generation, den \u00f6ffentlichen Raum im Borsigviertel mitgestalten m\u00f6chtest &#8211; Herzlich Willkommen! Ein vorgefertigtes Konzept gibt es nicht! Du bist der\/die Lokalexperten\/in. Keiner wei\u00df besser als Du, wie es sich in Deinem Viertel leben l\u00e4sst und &hellip;<\/p>\n","protected":false},"author":10,"featured_media":2469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178,173,1,147,136],"tags":[86,152,116,89,57,185],"class_list":["post-2468","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-178","category-aktionen","category-aktuell","category-angela-ljiljanic","category-public-residence","tag-borsigplatz","tag-chancen","tag-faktor-kunst","tag-kunst","tag-nachbarschaft","tag-public-residence"],"_links":{"self":[{"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/posts\/2468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2468"}],"version-history":[{"count":0,"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/posts\/2468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/media\/2469"}],"wp:attachment":[{"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.borsig11.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}